{"id":52865,"date":"2017-09-13T00:01:09","date_gmt":"2017-09-13T00:01:09","guid":{"rendered":"http:\/\/www.imhd.nl\/log\/?p=52865"},"modified":"2017-09-13T06:56:32","modified_gmt":"2017-09-13T06:56:32","slug":"137-vergeten","status":"publish","type":"post","link":"https:\/\/www.imhd.nl\/log\/137-vergeten\/","title":{"rendered":"137. vergeten"},"content":{"rendered":"<p><em>Vergeten dient een doel: niemand zou ooit nog een kind krijgen, of iemand anders liefhebben, als je wist hoeveel pijn het deed om het liefste te krijgen, en het op een dag te moeten verliezen.<\/em> <small>\u2013 Logboek van een onbarmhartig jaar, Connie Palmen<\/small><\/p>\n<p><!--- bvb, b3nt3 ---><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vergeten dient een doel: niemand zou ooit nog een kind krijgen, of iemand anders liefhebben, als je wist hoeveel pijn het deed om het liefste te krijgen, en het op een dag te moeten verliezen. \u2013 Logboek van een onbarmhartig jaar, Connie Palmen<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1714],"tags":[],"_links":{"self":[{"href":"https:\/\/www.imhd.nl\/log\/wp-json\/wp\/v2\/posts\/52865"}],"collection":[{"href":"https:\/\/www.imhd.nl\/log\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.imhd.nl\/log\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.imhd.nl\/log\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.imhd.nl\/log\/wp-json\/wp\/v2\/comments?post=52865"}],"version-history":[{"count":3,"href":"https:\/\/www.imhd.nl\/log\/wp-json\/wp\/v2\/posts\/52865\/revisions"}],"predecessor-version":[{"id":52984,"href":"https:\/\/www.imhd.nl\/log\/wp-json\/wp\/v2\/posts\/52865\/revisions\/52984"}],"wp:attachment":[{"href":"https:\/\/www.imhd.nl\/log\/wp-json\/wp\/v2\/media?parent=52865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.imhd.nl\/log\/wp-json\/wp\/v2\/categories?post=52865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.imhd.nl\/log\/wp-json\/wp\/v2\/tags?post=52865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}