{"id":25120,"date":"2012-12-16T12:52:10","date_gmt":"2012-12-16T10:52:10","guid":{"rendered":"http:\/\/www.irmadriessen.nl\/log\/?p=25120"},"modified":"2018-11-06T07:02:19","modified_gmt":"2018-11-06T07:02:19","slug":"london-2012","status":"publish","type":"post","link":"https:\/\/www.imhd.nl\/log\/london-2012\/","title":{"rendered":"london 2012"},"content":{"rendered":"<p>Twee beelden en \u00e9\u00e9n gedachte die ik wil bewaren: <\/p>\n<p>Er racen kleine auto&#8217;s over het veld, ze halen speren op bij het speerwerpen. De auto&#8217;s \u2013 merk Mini \u2013 zijn heel klein. <\/p>\n<p>Het kunstgrasveld is blauw, alsof de geest zich neerlegt bij het idee dat kunstgras, waar men al jaren op speelt, niet groen hoeft te zijn.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Twee beelden en \u00e9\u00e9n gedachte die ik wil bewaren: Er racen kleine auto&#8217;s over het veld, ze halen speren op bij het speerwerpen. De auto&#8217;s \u2013 merk Mini \u2013 zijn heel klein. Het kunstgrasveld is blauw, alsof de geest zich neerlegt bij het idee dat kunstgras, waar men al jaren op speelt, niet groen hoeft<a href=\"https:\/\/www.imhd.nl\/log\/london-2012\/\" class=\"read-more\">Read more &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[416,776],"_links":{"self":[{"href":"https:\/\/www.imhd.nl\/log\/wp-json\/wp\/v2\/posts\/25120"}],"collection":[{"href":"https:\/\/www.imhd.nl\/log\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.imhd.nl\/log\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.imhd.nl\/log\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.imhd.nl\/log\/wp-json\/wp\/v2\/comments?post=25120"}],"version-history":[{"count":1,"href":"https:\/\/www.imhd.nl\/log\/wp-json\/wp\/v2\/posts\/25120\/revisions"}],"predecessor-version":[{"id":58259,"href":"https:\/\/www.imhd.nl\/log\/wp-json\/wp\/v2\/posts\/25120\/revisions\/58259"}],"wp:attachment":[{"href":"https:\/\/www.imhd.nl\/log\/wp-json\/wp\/v2\/media?parent=25120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.imhd.nl\/log\/wp-json\/wp\/v2\/categories?post=25120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.imhd.nl\/log\/wp-json\/wp\/v2\/tags?post=25120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}